{"id":3129,"date":"2019-06-10T00:56:03","date_gmt":"2019-06-09T21:56:03","guid":{"rendered":"https:\/\/pew-pew.fi\/wp-content\/uploads\/2019\/06\/C83A0272.jpg"},"modified":"2019-06-10T00:56:03","modified_gmt":"2019-06-09T21:56:03","slug":"c83a0272-2","status":"inherit","type":"attachment","link":"https:\/\/pew-pew.fi\/en\/c83a0272-2\/","title":{"rendered":"C83A0272"},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"_links_to":"","_links_to_target":""},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/pew-pew.fi\/wp-content\/uploads\/2019\/06\/C83A0272.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"201\" height=\"300\" src=\"https:\/\/pew-pew.fi\/wp-content\/uploads\/2019\/06\/C83A0272-201x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/pew-pew.fi\/wp-content\/uploads\/2019\/06\/C83A0272-201x300.jpg 201w, https:\/\/pew-pew.fi\/wp-content\/uploads\/2019\/06\/C83A0272-768x1146.jpg 768w, https:\/\/pew-pew.fi\/wp-content\/uploads\/2019\/06\/C83A0272-686x1024.jpg 686w, https:\/\/pew-pew.fi\/wp-content\/uploads\/2019\/06\/C83A0272.jpg 1372w\" sizes=\"(max-width: 201px) 100vw, 201px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1372,"height":2048,"file":"2019\/06\/C83A0272.jpg","sizes":{"thumbnail":{"file":"C83A0272-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/pew-pew.fi\/wp-content\/uploads\/2019\/06\/C83A0272-150x150.jpg"},"medium":{"file":"C83A0272-201x300.jpg","width":201,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/pew-pew.fi\/wp-content\/uploads\/2019\/06\/C83A0272-201x300.jpg"},"medium_large":{"file":"C83A0272-768x1146.jpg","width":768,"height":1146,"mime_type":"image\/jpeg","source_url":"https:\/\/pew-pew.fi\/wp-content\/uploads\/2019\/06\/C83A0272-768x1146.jpg"},"large":{"file":"C83A0272-686x1024.jpg","width":686,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/pew-pew.fi\/wp-content\/uploads\/2019\/06\/C83A0272-686x1024.jpg"},"colormag-highlighted-post":{"file":"C83A0272-392x272.jpg","width":392,"height":272,"mime_type":"image\/jpeg","source_url":"https:\/\/pew-pew.fi\/wp-content\/uploads\/2019\/06\/C83A0272-392x272.jpg"},"colormag-featured-post-medium":{"file":"C83A0272-390x205.jpg","width":390,"height":205,"mime_type":"image\/jpeg","source_url":"https:\/\/pew-pew.fi\/wp-content\/uploads\/2019\/06\/C83A0272-390x205.jpg"},"colormag-featured-post-small":{"file":"C83A0272-130x90.jpg","width":130,"height":90,"mime_type":"image\/jpeg","source_url":"https:\/\/pew-pew.fi\/wp-content\/uploads\/2019\/06\/C83A0272-130x90.jpg"},"colormag-featured-image":{"file":"C83A0272-800x445.jpg","width":800,"height":445,"mime_type":"image\/jpeg","source_url":"https:\/\/pew-pew.fi\/wp-content\/uploads\/2019\/06\/C83A0272-800x445.jpg"},"full":{"file":"C83A0272.jpg","width":1372,"height":2048,"mime_type":"image\/jpeg","source_url":"https:\/\/pew-pew.fi\/wp-content\/uploads\/2019\/06\/C83A0272.jpg"}},"image_meta":{"aperture":"2","credit":"","camera":"Canon EOS 5D Mark III","caption":"","created_timestamp":"1560096777","copyright":"","focal_length":"135","iso":"800","shutter_speed":"0.003125","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/pew-pew.fi\/wp-content\/uploads\/2019\/06\/C83A0272.jpg","_links":{"self":[{"href":"https:\/\/pew-pew.fi\/en\/wp-json\/wp\/v2\/media\/3129"}],"collection":[{"href":"https:\/\/pew-pew.fi\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/pew-pew.fi\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/pew-pew.fi\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/pew-pew.fi\/en\/wp-json\/wp\/v2\/comments?post=3129"}]}}